{"id":28922,"date":"2020-09-02T16:47:17","date_gmt":"2020-09-02T20:47:17","guid":{"rendered":"https:\/\/www.nautilusplus.com\/fr\/?p=28922"},"modified":"2020-09-02T16:47:17","modified_gmt":"2020-09-02T20:47:17","slug":"gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets","status":"publish","type":"post","link":"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/","title":{"rendered":"Gaufres au zeste de citron et graines de pavot avec coulis aux bleuets"},"content":{"rendered":"<p>Aaah les longs week-ends! Ils sont souvent synonymes de\u00a0moments o\u00f9 l\u2019on passe du temps avec nos proches autour d\u2019un brunch. C\u2019est tout simplement une belle occasion pour se rassembler&#8230; en respectant la distanciation bien s\u00fbr! \ud83d\ude09<br \/>\nAlors, pourquoi pas c\u00e9l\u00e9brer la f\u00eate du travail en d\u00e9butant la journ\u00e9e avec des gaufres maison au petit d\u00e9jeuner?<\/p>\n<p>Temps de pr\u00e9paration : 15 minutes<\/p>\n<p>Temps de cuisson : 15 minutes<\/p>\n<p>Donne 4 portions<\/p>\n<h2>Ingr\u00e9dients pour les gaufres<\/h2>\n<ul>\n<li>2 \u00bc tasses de flocons d\u2019avoine<\/li>\n<li>1 c. \u00e0 th\u00e9 de bicarbonate de soude<\/li>\n<li>\u00bd c. \u00e0 th\u00e9 de sel<\/li>\n<li>2 \u0153ufs<\/li>\n<li>2 c. \u00e0 soupe de sirop d\u2019\u00e9rable<\/li>\n<li>1 c. \u00e0 th\u00e9 d\u2019extrait de vanille<\/li>\n<li>1 c. \u00e0 soupe de zeste de citron<\/li>\n<li>\u00bc tasse de jus de citron fra\u00eechement press\u00e9 (l\u2019\u00e9quivalent du jus d\u2019un citron)<\/li>\n<li>1 \u00bd tasse de lait d\u2019avoine non sucr\u00e9<\/li>\n<li>1 c. \u00e0 soupe de graines de pavot<\/li>\n<li>Vaporisateur d\u2019huile v\u00e9g\u00e9tale<\/li>\n<\/ul>\n<h2>Ingr\u00e9dients pour le coulis aux bleuets<\/h2>\n<ul>\n<li>1 tasse de yogourt l\u00e9ger \u00e0 la vanille<\/li>\n<li>\u00bd tasse de bleuets<\/li>\n<\/ul>\n<h2>\u00c9tapes pour les gaufres<\/h2>\n<ol>\n<li>Allumer le gaufrier \u00e0 temp\u00e9rature moyenne.<\/li>\n<li>Dans un m\u00e9langeur \u00e9lectrique, r\u00e9duire les flocons d\u2019avoine en farine.<\/li>\n<li>Ajouter le bicarbonate de soude et le sel. Puis, m\u00e9langer.<\/li>\n<li>Dans un bol \u00e0 part, m\u00e9langer les \u0153ufs, le sirop d\u2019\u00e9rable, la vanille, le zeste de citron, le jus de citron et le lait d\u2019avoine.<\/li>\n<li>Incorporer les ingr\u00e9dients humides aux ingr\u00e9dients secs dans le m\u00e9langeur et m\u00e9langer jusqu\u2019\u00e0 l\u2019obtention d\u2019une texture homog\u00e8ne.<\/li>\n<li>Ajouter les graines de pavot au m\u00e9lange et brasser \u00e0 l\u2019aide d\u2019une cuill\u00e8re simplement pour distribuer les graines uniform\u00e9ment.<\/li>\n<li>Vaporiser le gaufrier \u00e0 l\u2019aide d\u2019un vaporisateur d\u2019huile v\u00e9g\u00e9tale.<\/li>\n<li>D\u00e9poser le m\u00e9lange dans le gaufrier et fermer le couvercle. Cuire jusqu\u2019\u00e0 ce que la gaufre soit dor\u00e9e et croustillante. Puis, r\u00e9p\u00e9ter.<\/li>\n<\/ol>\n<h2>\u00c9tapes pour le coulis aux bleuets<\/h2>\n<ol>\n<li>Dans un m\u00e9langeur, m\u00e9langer \u00e0 haute vitesse le yogourt et les bleuets.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h3>Valeurs nutritives par portion : 388 calories, 7 g lipides, 59 g glucides, 7 g fibres, 17 g prot\u00e9ines<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Aaah les longs week-ends! Ils sont souvent synonymes de\u00a0moments o\u00f9 l\u2019on passe du temps avec nos proches autour d\u2019un brunch. C\u2019est tout simplement une belle occasion pour se rassembler&#8230; en respectant la distanciation bien s\u00fbr! \ud83d\ude09 Alors, pourquoi pas c\u00e9l\u00e9brer la f\u00eate du travail en d\u00e9butant la journ\u00e9e avec des gaufres maison au petit d\u00e9jeuner? [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":28923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5190,1267],"tags":[2042,3027,1648,5549],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<meta name=\"description\" content=\"Planifier vous un brunch pour ce weekend? Pourquoi pas c\u00e9l\u00e9brer la f\u00eate du travail en d\u00e9butant la journ\u00e9e avec des gaufres faites maison au petit d\u00e9jeuner?\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Gaufres au zeste de citron et graines de pavot avec coulis aux bleuets - Nautilus Plus\" \/>\r\n<meta property=\"og:description\" content=\"Planifier vous un brunch pour ce weekend? Pourquoi pas c\u00e9l\u00e9brer la f\u00eate du travail en d\u00e9butant la journ\u00e9e avec des gaufres faites maison au petit d\u00e9jeuner?\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Nautilus Plus\" \/>\r\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nautilusplus\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-09-02T20:47:17+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/08\/gaufre-citron-graines-de-pavot_QBalthazard-blogue-cover.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"6000\" \/>\r\n\t<meta property=\"og:image:height\" content=\"4000\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#website\",\"url\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"name\":\"Nautilus Plus\",\"description\":\"Plus qu&#039;un gym\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.nautilusplus.com\/fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/08\/gaufre-citron-graines-de-pavot_QBalthazard-blogue-cover.jpg\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/08\/gaufre-citron-graines-de-pavot_QBalthazard-blogue-cover.jpg\",\"width\":6000,\"height\":4000,\"caption\":\"gaufre-citron-bleuet-brunch\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/#webpage\",\"url\":\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/\",\"name\":\"Gaufres au zeste de citron et graines de pavot avec coulis aux bleuets - Nautilus Plus\",\"isPartOf\":{\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/#primaryimage\"},\"datePublished\":\"2020-09-02T20:47:17+00:00\",\"dateModified\":\"2020-09-02T20:47:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#\/schema\/person\/d1896eeaebe531fd4af7f22e29ceb51a\"},\"description\":\"Planifier vous un brunch pour ce weekend? Pourquoi pas c\\u00e9l\\u00e9brer la f\\u00eate du travail en d\\u00e9butant la journ\\u00e9e avec des gaufres faites maison au petit d\\u00e9jeuner?\",\"breadcrumb\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"url\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gaufres-au-zeste-de-citron-et-graines-de-pavot-avec-coulis-aux-bleuets\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#\/schema\/person\/d1896eeaebe531fd4af7f22e29ceb51a\",\"name\":\"Nautilus Plus\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/03\/NautilusPlus_fond-bleu-96x96.jpg\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/03\/NautilusPlus_fond-bleu-96x96.jpg\",\"caption\":\"Nautilus Plus\"},\"sameAs\":[\"http:\/\/www.NautilusPlus.com\",\"https:\/\/www.facebook.com\/nautilusplus\",\"https:\/\/twitter.com\/Nautilus_Plus\"],\"url\":\"https:\/\/cms.nautilusplus.com\/fr\/author\/nautilusplus\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/28922"}],"collection":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/comments?post=28922"}],"version-history":[{"count":0,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/28922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media\/28923"}],"wp:attachment":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media?parent=28922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/categories?post=28922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/tags?post=28922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}