{"id":27932,"date":"2019-07-03T10:35:34","date_gmt":"2019-07-03T14:35:34","guid":{"rendered":"https:\/\/www.nautilusplus.com\/fr\/?p=27932"},"modified":"2021-11-22T15:15:21","modified_gmt":"2021-11-22T20:15:21","slug":"demystifier-le-jeune-intermittent","status":"publish","type":"post","link":"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/","title":{"rendered":"D\u00e9mystifier le je\u00fbne intermittent"},"content":{"rendered":"<p>Un mode alimentaire tr\u00e8s tendance ces derniers temps est le je\u00fbne intermittent, aussi appel\u00e9 <em>fasting,<\/em>&nbsp;comme m\u00e9thode de perte de poids.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Qu\u2019est-ce que c\u2019est? <\/strong><\/h2>\n<p>Le je\u00fbne intermittent consiste \u00e0 <strong>alterner des p\u00e9riodes de je\u00fbne et des p\u00e9riodes de prises alimentaires<\/strong>. Il en existe plusieurs d\u00e9clinaisons, dont le 16&nbsp;:8 qui est le plus commun.<\/p>\n<p>Il consiste \u00e0 ne rien manger pendant une p\u00e9riode de 16 \u00e0 20 heures, pour ensuite manger normalement pendant 4 \u00e0 8 heures. Les heures de prises alimentaires sont flexibles, c\u2019est-\u00e0-dire que l\u2019on peut manger de 10h-18h ou de 12h-20h, etc.<\/p>\n<p>Les adeptes du je\u00fbne intermittent mentionnent entre autres <strong>un niveau d\u2019\u00e9nergie plus \u00e9lev\u00e9, un meilleur sommeil et une perte de poids significative<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Comment \u00e7a fonctionne? <\/strong><\/h2>\n<p>En fait, si l\u2019on d\u00e9cortique cette fa\u00e7on de s\u2019alimenter, le corps est nourri pendant 8 heures. Prenons en exemple une personne qui doit consommer 2000 calories pour maintenir son poids. Cela signifie consommer 666 calories divis\u00e9es en 3 repas, <strong>soit 666 calories \u00e0 chaque 2,5 heures<\/strong>. Difficile de manger tout cela en si peu de temps, direz-vous? Moi aussi je trouve.<\/p>\n<p>Ainsi, l\u2019apport \u00e9nerg\u00e9tique total est instinctivement diminu\u00e9 par la personne qui je\u00fbne, car celle-ci diminue les opportunit\u00e9s de manger. Certains mangeront 2 repas, certains 2 repas et 1 collation, mais rarement y aura-t-il 3 repas.<\/p>\n<p>Au final, il y a moins de calories consomm\u00e9es par jour et donc une perte de poids s\u2019ensuite. Le je\u00fbne intermittent s\u2019apparente ainsi \u00e0 une simple restriction calorique, tel qu\u2019il peut l\u2019\u00eatre fait lors d\u2019une d\u00e9marche de perte de poids accompagn\u00e9e d\u2019une nutritionniste.<\/p>\n<p>&nbsp;<\/p>\n<h2>Mon opinion<\/h2>\n<p>Est-ce que je conseille le je\u00fbne intermittent aux gens d\u00e9sirant entamer une d\u00e9marche de perte de poids? La r\u00e9ponse est non. En consultation, j\u2019ai vu \u00e0 quelques reprises des gens refuser des sorties au restaurant avec des amis, puisque cela leur aurait demand\u00e9 de \u00abbriser\u00bb leur je\u00fbne. \u00c0 mon avis, il y a des fa\u00e7ons plus simples, et qui ne n\u00e9cessitent pas de restreindre les heures de repas dans un cadre fixe ou de s\u2019emp\u00eacher de sortir. Cet article d&rsquo;Eva Lalonde, nutritionniste chez Nautilus Plus, vous explique <a href=\"https:\/\/www.nautilusplus.com\/fr\/5-astuces-de-nutritionniste-pour-perdre-du-poids-en-douceur\/\">5 fa\u00e7ons de perdre du poids en douceur<\/a>, sans vous restreindre. Enfin, <a href=\"http:\/\/www.contact.ulaval.ca\/article_blogue\/jeune-intermittent-perte-de-poids\/\">comme l\u2019explique Simone Lemieux, professeure \u00e0 l\u2019\u00c9cole de nutrition de l\u2019universit\u00e9 Laval<\/a>, je doute sur la compatibilit\u00e9 entre un je\u00fbne et la pratique d\u2019activit\u00e9 physique de moyenne \u00e0 haute intensit\u00e9.<\/p>\n<p>Au final, il revient \u00e0 chacun de choisir la m\u00e9thode dont il d\u00e9sire s\u2019alimenter, toutefois, je conseille fortement de peser le pour et le contre avant d\u2019entreprendre un r\u00e9gime quelque peu restrictif.<\/p>\n<p>&nbsp;<\/p>\n<h3>R\u00e9f\u00e9rences<\/h3>\n<p><a href=\"https:\/\/www.nautilusplus.com\/fr\/5-astuces-de-nutritionniste-pour-perdre-du-poids-en-douceur\/\">https:\/\/www.nautilusplus.com\/fr\/5-astuces-de-nutritionniste-pour-perdre-du-poids-en-douceur\/<\/a><\/p>\n<p><a href=\"http:\/\/www.contact.ulaval.ca\/article_blogue\/jeune-intermittent-perte-de-poids\/\">http:\/\/www.contact.ulaval.ca\/article_blogue\/jeune-intermittent-perte-de-poids\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un mode alimentaire tr\u00e8s tendance ces derniers temps est le je\u00fbne intermittent, aussi appel\u00e9 fasting,&nbsp;comme m\u00e9thode de perte de poids. &nbsp; Qu\u2019est-ce que c\u2019est? Le je\u00fbne intermittent consiste \u00e0 alterner des p\u00e9riodes de je\u00fbne et des p\u00e9riodes de prises alimentaires. Il en existe plusieurs d\u00e9clinaisons, dont le 16&nbsp;:8 qui est le plus commun. Il consiste [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":27938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5681,5193],"tags":[2644,4938,5384,1321,2649],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<meta name=\"description\" content=\"Un mode alimentaire tr\u00e8s tendance ces derniers temps est le je\u00fbne intermittent aussi appel\u00e9 fasting comme m\u00e9thode de perte de poids.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"D\u00e9mystifier le je\u00fbne intermittent - Nautilus Plus\" \/>\r\n<meta property=\"og:description\" content=\"Un mode alimentaire tr\u00e8s tendance ces derniers temps est le je\u00fbne intermittent aussi appel\u00e9 fasting comme m\u00e9thode de perte de poids.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Nautilus Plus\" \/>\r\n<meta property=\"article:published_time\" content=\"2019-07-03T14:35:34+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-11-22T20:15:21+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.nautilusplus.com\/content\/uploads\/2019\/06\/Blogue_jeune-intermittent.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"940\" \/>\r\n\t<meta property=\"og:image:height\" content=\"788\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nautilusplus.com\/#website\",\"url\":\"https:\/\/www.nautilusplus.com\/\",\"name\":\"Nautilus Plus\",\"description\":\"Plus qu&#039;un gym\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.nautilusplus.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2019\/06\/Blogue_jeune-intermittent.png\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2019\/06\/Blogue_jeune-intermittent.png\",\"width\":940,\"height\":788,\"caption\":\"Personne mangeant son repas\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/#webpage\",\"url\":\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/\",\"name\":\"D\\u00e9mystifier le je\\u00fbne intermittent - Nautilus Plus\",\"isPartOf\":{\"@id\":\"https:\/\/www.nautilusplus.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/#primaryimage\"},\"datePublished\":\"2019-07-03T14:35:34+00:00\",\"dateModified\":\"2021-11-22T20:15:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.nautilusplus.com\/#\/schema\/person\/217f6dd01f26ff0185dd41662007b3bd\"},\"description\":\"Un mode alimentaire tr\\u00e8s tendance ces derniers temps est le je\\u00fbne intermittent aussi appel\\u00e9 fasting comme m\\u00e9thode de perte de poids.\",\"breadcrumb\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"url\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/demystifier-le-jeune-intermittent\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nautilusplus.com\/#\/schema\/person\/217f6dd01f26ff0185dd41662007b3bd\",\"name\":\"Am\\u00e9lie Deschamps\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.nautilusplus.com\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/06\/adeschamps-2-96x96.jpg\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/06\/adeschamps-2-96x96.jpg\",\"caption\":\"Am\\u00e9lie Deschamps\"},\"description\":\"Am\\u00e9lie obtained her Nutrition and Dietetics degree from Laval University in 2017 and is a member of the Ordre des professionnels di\\u00e9t\\u00e9tistes du Qu\\u00e9bec. She began her career at Nautilus Plus as shift supervisor in 2016 and has been on our team of nutritionists since January 2018. Passionate about running and triathlons, Am\\u00e9lie specializes in sports nutrition because she believes that sports and healthy nutrition are one and the same. In 2017, she completed a 15 hour training course on nutrition and micronutrition for endurance sports and is currently considering the International Olympic Committee diploma in sports nutrition. She is also interested in the weight loss process, building muscle mass, as well as writing articles and giving conferences on the benefits of healthy eating. She believes in eating without restrictions and focuses rather on proper balance and pleasing the palate.\",\"url\":\"https:\/\/cms.nautilusplus.com\/fr\/author\/adeschamps\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/27932"}],"collection":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/comments?post=27932"}],"version-history":[{"count":0,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/27932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media\/27938"}],"wp:attachment":[{"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media?parent=27932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/categories?post=27932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms.nautilusplus.com\/fr\/wp-json\/wp\/v2\/tags?post=27932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}